{"id":178,"count":3,"description":"Buscar el benestar \u00e9s l'objectiu de la vida, ja sigui a trav\u00e9s de la llibertat, la salut o, simplement, el confort. Utility sempre serveix per solucionar temes puntuals que s\u00f3n molestos, aportant ess\u00e8ncia natural a petits problemes puntuals, des d'uns mosquits a l'estiu a unes males olors d'armari o de bany...","link":"https:\/\/www.shizenna.com\/es\/productos\/utility\/","name":"Utility","slug":"utility","taxonomy":"product_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Utility archivos - Shizen&#039;na<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shizenna.com\/es\/productos\/utility\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Utility archivos - Shizen&#039;na\" \/>\n<meta property=\"og:description\" content=\"Buscar el benestar \u00e9s l&#8217;objectiu de la vida, ja sigui a trav\u00e9s de la llibertat, la salut o, simplement, el confort. Utility sempre serveix per solucionar temes puntuals que s\u00f3n molestos, aportant ess\u00e8ncia natural a petits problemes puntuals, des d&#8217;uns mosquits a l&#8217;estiu a unes males olors d&#8217;armari o de bany&#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shizenna.com\/es\/productos\/utility\/\" \/>\n<meta property=\"og:site_name\" content=\"Shizen&#039;na\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.shizenna.com\/en\/productos\/utility\/\",\"url\":\"https:\/\/www.shizenna.com\/en\/productos\/utility\/\",\"name\":\"Utility archivos - Shizen&#039;na\",\"isPartOf\":{\"@id\":\"https:\/\/www.shizenna.com\/#website\"},\"inLanguage\":\"es\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.shizenna.com\/#website\",\"url\":\"https:\/\/www.shizenna.com\/\",\"name\":\"Shizen&#039;na\",\"description\":\"Respira 100% natural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.shizenna.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Utility archivos - Shizen&#039;na","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shizenna.com\/es\/productos\/utility\/","og_locale":"es_ES","og_type":"article","og_title":"Utility archivos - Shizen&#039;na","og_description":"Buscar el benestar \u00e9s l&#8217;objectiu de la vida, ja sigui a trav\u00e9s de la llibertat, la salut o, simplement, el confort. Utility sempre serveix per solucionar temes puntuals que s\u00f3n molestos, aportant ess\u00e8ncia natural a petits problemes puntuals, des d&#8217;uns mosquits a l&#8217;estiu a unes males olors d&#8217;armari o de bany&#8230;","og_url":"https:\/\/www.shizenna.com\/es\/productos\/utility\/","og_site_name":"Shizen&#039;na","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.shizenna.com\/en\/productos\/utility\/","url":"https:\/\/www.shizenna.com\/en\/productos\/utility\/","name":"Utility archivos - Shizen&#039;na","isPartOf":{"@id":"https:\/\/www.shizenna.com\/#website"},"inLanguage":"es"},{"@type":"WebSite","@id":"https:\/\/www.shizenna.com\/#website","url":"https:\/\/www.shizenna.com\/","name":"Shizen&#039;na","description":"Respira 100% natural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shizenna.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.shizenna.com\/es\/wp-json\/wp\/v2\/product_cat\/178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shizenna.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.shizenna.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.shizenna.com\/es\/wp-json\/wp\/v2\/product?product_cat=178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}